{"id":13284,"date":"2024-08-14T15:32:53","date_gmt":"2024-08-14T14:32:53","guid":{"rendered":"https:\/\/pcg.io\/?post_type=insight&#038;p=13284"},"modified":"2026-01-21T09:15:56","modified_gmt":"2026-01-21T08:15:56","slug":"pcg-aws-smb-competency","status":"publish","type":"insight","link":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/","title":{"rendered":"PCG erh\u00e4lt weitere AWS-Kompetenz: Kleine und mittlere Unternehmen"},"author":9,"featured_media":0,"template":"","meta":{"_acf_changed":false},"tags":[],"class_list":["post-13284","insight","type-insight","status-publish","hentry","insight_type-press-release"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PCG erwirbt weitere AWS-Kompetenz<\/title>\n<meta name=\"description\" content=\"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCG erwirbt weitere AWS-Kompetenz\" \/>\n<meta property=\"og:description\" content=\"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/\" \/>\n<meta property=\"og:site_name\" content=\"PCG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T08:15:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/pcg-aws-smb-competency\\\/\",\"url\":\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/pcg-aws-smb-competency\\\/\",\"name\":\"PCG erwirbt weitere AWS-Kompetenz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pcg.io\\\/de\\\/#website\"},\"datePublished\":\"2024-08-14T14:32:53+00:00\",\"dateModified\":\"2026-01-21T08:15:56+00:00\",\"description\":\"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/pcg-aws-smb-competency\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/pcg-aws-smb-competency\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/pcg-aws-smb-competency\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pcg.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/pcg.io\\\/de\\\/insights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCG erh\u00e4lt weitere AWS-Kompetenz: Kleine und mittlere Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pcg.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pcg.io\\\/de\\\/\",\"name\":\"PCG\",\"description\":\"Your Cloud Journey, Simplified.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pcg.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PCG erwirbt weitere AWS-Kompetenz","description":"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/","og_locale":"de_DE","og_type":"article","og_title":"PCG erwirbt weitere AWS-Kompetenz","og_description":"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.","og_url":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/","og_site_name":"PCG","article_modified_time":"2026-01-21T08:15:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/","url":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/","name":"PCG erwirbt weitere AWS-Kompetenz","isPartOf":{"@id":"https:\/\/pcg.io\/de\/#website"},"datePublished":"2024-08-14T14:32:53+00:00","dateModified":"2026-01-21T08:15:56+00:00","description":"AWS SMB-Kompetenz f\u00fcr PCG in Deutschland: Nutzen Sie unsere Cloud-Expertise f\u00fcr KMU, um Flexibilit\u00e4t zu steigern und Kosten zu optimieren.","breadcrumb":{"@id":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pcg.io\/de\/insights\/pcg-aws-smb-competency\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pcg.io\/de\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/pcg.io\/de\/insights\/"},{"@type":"ListItem","position":3,"name":"PCG erh\u00e4lt weitere AWS-Kompetenz: Kleine und mittlere Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/pcg.io\/de\/#website","url":"https:\/\/pcg.io\/de\/","name":"PCG","description":"Your Cloud Journey, Simplified.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pcg.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/insight\/13284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/insight"}],"about":[{"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/types\/insight"}],"author":[{"embeddable":true,"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/users\/9"}],"wp:attachment":[{"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/media?parent=13284"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcg.io\/de\/wp-json\/wp\/v2\/tags?post=13284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}